{"id":310,"count":24,"description":"","link":"https:\/\/www.deepseareporter.com\/sv\/tag\/arktis\/","name":"Arktis","slug":"arktis","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Arktis Arkiv - Deep Sea Reporter<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deepseareporter.com\/tag\/arktis\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arktis Arkiv - Deep Sea Reporter\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deepseareporter.com\/tag\/arktis\/\" \/>\n<meta property=\"og:site_name\" content=\"Deep Sea Reporter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.deepseareporter.com\/tag\/arktis\/\",\"url\":\"https:\/\/www.deepseareporter.com\/tag\/arktis\/\",\"name\":\"Arktis Arkiv - Deep Sea Reporter\",\"isPartOf\":{\"@id\":\"https:\/\/www.deepseareporter.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.deepseareporter.com\/tag\/arktis\/#breadcrumb\"},\"inLanguage\":\"sv-SE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.deepseareporter.com\/tag\/arktis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\/\/www.deepseareporter.com\/sv\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arktis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.deepseareporter.com\/#website\",\"url\":\"https:\/\/www.deepseareporter.com\/\",\"name\":\"Deep Sea Reporter\",\"description\":\"Ett digitalt magasin om havet\",\"publisher\":{\"@id\":\"https:\/\/www.deepseareporter.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.deepseareporter.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.deepseareporter.com\/#organization\",\"name\":\"Deep Sea Reporter\",\"url\":\"https:\/\/www.deepseareporter.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\/\/www.deepseareporter.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.deepseareporter.com\/wp-content\/uploads\/2024\/10\/dsr-bla-ny-logga.svg\",\"contentUrl\":\"https:\/\/www.deepseareporter.com\/wp-content\/uploads\/2024\/10\/dsr-bla-ny-logga.svg\",\"width\":834,\"height\":504,\"caption\":\"Deep Sea Reporter\"},\"image\":{\"@id\":\"https:\/\/www.deepseareporter.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arktis Arkiv - Deep Sea Reporter","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deepseareporter.com\/tag\/arktis\/","og_locale":"sv_SE","og_type":"article","og_title":"Arktis Arkiv - Deep Sea Reporter","og_url":"https:\/\/www.deepseareporter.com\/tag\/arktis\/","og_site_name":"Deep Sea Reporter","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.deepseareporter.com\/tag\/arktis\/","url":"https:\/\/www.deepseareporter.com\/tag\/arktis\/","name":"Arktis Arkiv - Deep Sea Reporter","isPartOf":{"@id":"https:\/\/www.deepseareporter.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.deepseareporter.com\/tag\/arktis\/#breadcrumb"},"inLanguage":"sv-SE"},{"@type":"BreadcrumbList","@id":"https:\/\/www.deepseareporter.com\/tag\/arktis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/www.deepseareporter.com\/sv\/"},{"@type":"ListItem","position":2,"name":"Arktis"}]},{"@type":"WebSite","@id":"https:\/\/www.deepseareporter.com\/#website","url":"https:\/\/www.deepseareporter.com\/","name":"Deep Sea Reporter","description":"Ett digitalt magasin om havet","publisher":{"@id":"https:\/\/www.deepseareporter.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deepseareporter.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sv-SE"},{"@type":"Organization","@id":"https:\/\/www.deepseareporter.com\/#organization","name":"Deep Sea Reporter","url":"https:\/\/www.deepseareporter.com\/","logo":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/www.deepseareporter.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.deepseareporter.com\/wp-content\/uploads\/2024\/10\/dsr-bla-ny-logga.svg","contentUrl":"https:\/\/www.deepseareporter.com\/wp-content\/uploads\/2024\/10\/dsr-bla-ny-logga.svg","width":834,"height":504,"caption":"Deep Sea Reporter"},"image":{"@id":"https:\/\/www.deepseareporter.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.deepseareporter.com\/sv\/wp-json\/wp\/v2\/tags\/310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deepseareporter.com\/sv\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.deepseareporter.com\/sv\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.deepseareporter.com\/sv\/wp-json\/wp\/v2\/posts?tags=310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}